{"id":2273,"date":"2016-02-25T11:39:46","date_gmt":"2016-02-25T10:39:46","guid":{"rendered":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2016\/02\/stiftung_umweltenergierecht_juni-2013.pdf"},"modified":"2016-02-25T11:39:46","modified_gmt":"2016-02-25T10:39:46","slug":"stiftung_umweltenergierecht_juni-2013-2","status":"inherit","type":"attachment","link":"https:\/\/stiftung-umweltenergierecht.de\/en\/stiftung_umweltenergierecht_juni-2013-2\/","title":{"rendered":"stiftung_umweltenergierecht_juni 2013"},"author":45,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-2273","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>stiftung_umweltenergierecht_juni 2013 - Stiftung Umweltenergierecht<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2016\/02\/stiftung_umweltenergierecht_juni-2013.pdf\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"stiftung_umweltenergierecht_juni 2013 - Stiftung Umweltenergierecht\" \/>\n<meta property=\"og:description\" content=\"stiftung_umweltenergierecht_juni 2013\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2016\/02\/stiftung_umweltenergierecht_juni-2013.pdf\" \/>\n<meta property=\"og:site_name\" content=\"Stiftung Umweltenergierecht\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/stiftung_umweltenergierecht_juni-2013.pdf\",\"url\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/stiftung_umweltenergierecht_juni-2013.pdf\",\"name\":\"stiftung_umweltenergierecht_juni 2013 - Stiftung Umweltenergierecht\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/#website\"},\"datePublished\":\"2016-02-25T10:39:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/stiftung_umweltenergierecht_juni-2013.pdf#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/stiftung_umweltenergierecht_juni-2013.pdf\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/stiftung_umweltenergierecht_juni-2013.pdf#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"stiftung_umweltenergierecht_juni 2013\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/#website\",\"url\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/\",\"name\":\"Stiftung Umweltenergierecht\",\"description\":\"Eine weitere WordPress-Seite\",\"publisher\":{\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/#organization\",\"name\":\"Stiftung Umweltenergierecht\",\"url\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/logo-SUER_web.jpg\",\"contentUrl\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/logo-SUER_web.jpg\",\"width\":493,\"height\":53,\"caption\":\"Stiftung Umweltenergierecht\"},\"image\":{\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"stiftung_umweltenergierecht_juni 2013 - Stiftung Umweltenergierecht","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2016\/02\/stiftung_umweltenergierecht_juni-2013.pdf","og_locale":"en_US","og_type":"article","og_title":"stiftung_umweltenergierecht_juni 2013 - Stiftung Umweltenergierecht","og_description":"stiftung_umweltenergierecht_juni 2013","og_url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2016\/02\/stiftung_umweltenergierecht_juni-2013.pdf","og_site_name":"Stiftung Umweltenergierecht","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2016\/02\/stiftung_umweltenergierecht_juni-2013.pdf","url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2016\/02\/stiftung_umweltenergierecht_juni-2013.pdf","name":"stiftung_umweltenergierecht_juni 2013 - Stiftung Umweltenergierecht","isPartOf":{"@id":"https:\/\/stiftung-umweltenergierecht.de\/#website"},"datePublished":"2016-02-25T10:39:46+00:00","breadcrumb":{"@id":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2016\/02\/stiftung_umweltenergierecht_juni-2013.pdf#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2016\/02\/stiftung_umweltenergierecht_juni-2013.pdf"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2016\/02\/stiftung_umweltenergierecht_juni-2013.pdf#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stiftung-umweltenergierecht.de\/en\/"},{"@type":"ListItem","position":2,"name":"stiftung_umweltenergierecht_juni 2013"}]},{"@type":"WebSite","@id":"https:\/\/stiftung-umweltenergierecht.de\/#website","url":"https:\/\/stiftung-umweltenergierecht.de\/","name":"Stiftung Umweltenergierecht","description":"Eine weitere WordPress-Seite","publisher":{"@id":"https:\/\/stiftung-umweltenergierecht.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stiftung-umweltenergierecht.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stiftung-umweltenergierecht.de\/#organization","name":"Stiftung Umweltenergierecht","url":"https:\/\/stiftung-umweltenergierecht.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stiftung-umweltenergierecht.de\/#\/schema\/logo\/image\/","url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2016\/03\/logo-SUER_web.jpg","contentUrl":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2016\/03\/logo-SUER_web.jpg","width":493,"height":53,"caption":"Stiftung Umweltenergierecht"},"image":{"@id":"https:\/\/stiftung-umweltenergierecht.de\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2016\/02\/stiftung_umweltenergierecht_juni-2013.pdf'>stiftung_umweltenergierecht_juni 2013<\/a><\/p>\n"},"caption":{"rendered":"<p>stiftung_umweltenergierecht_juni 2013<\/p>\n"},"alt_text":"","media_type":"file","mime_type":"application\/pdf","media_details":{},"post":null,"source_url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2016\/02\/stiftung_umweltenergierecht_juni-2013.pdf","filename":"stiftung_umweltenergierecht_juni-2013.pdf","filesize":463858,"_links":{"self":[{"href":"https:\/\/stiftung-umweltenergierecht.de\/en\/wp-json\/wp\/v2\/media\/2273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stiftung-umweltenergierecht.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/stiftung-umweltenergierecht.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/stiftung-umweltenergierecht.de\/en\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/stiftung-umweltenergierecht.de\/en\/wp-json\/wp\/v2\/comments?post=2273"}]}}