{"id":17276,"date":"2018-10-31T12:38:29","date_gmt":"2018-10-31T11:38:29","guid":{"rendered":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/10\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide.pdf"},"modified":"2025-08-19T12:16:31","modified_gmt":"2025-08-19T10:16:31","slug":"stiftung_umweltenergierecht_20181023_fokuseu_neuer_eu-rechtsrahmen_ide-2","status":"inherit","type":"attachment","link":"https:\/\/stiftung-umweltenergierecht.de\/en\/stiftung_umweltenergierecht_20181023_fokuseu_neuer_eu-rechtsrahmen_ide-2\/","title":{"rendered":"Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide"},"author":45,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-17276","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide - Stiftung Umweltenergierecht<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/10\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide.pdf\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide - Stiftung Umweltenergierecht\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/10\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide.pdf\" \/>\n<meta property=\"og:site_name\" content=\"Stiftung Umweltenergierecht\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-19T10:16:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide.pdf\",\"url\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide.pdf\",\"name\":\"Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide - Stiftung Umweltenergierecht\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/#website\"},\"datePublished\":\"2018-10-31T11:38:29+00:00\",\"dateModified\":\"2025-08-19T10:16:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide.pdf#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide.pdf\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide.pdf#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/#website\",\"url\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/\",\"name\":\"Stiftung Umweltenergierecht\",\"description\":\"Eine weitere WordPress-Seite\",\"publisher\":{\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/#organization\",\"name\":\"Stiftung Umweltenergierecht\",\"url\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/logo-SUER_web.jpg\",\"contentUrl\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/logo-SUER_web.jpg\",\"width\":493,\"height\":53,\"caption\":\"Stiftung Umweltenergierecht\"},\"image\":{\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide - Stiftung Umweltenergierecht","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/10\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide.pdf","og_locale":"en_US","og_type":"article","og_title":"Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide - Stiftung Umweltenergierecht","og_url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/10\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide.pdf","og_site_name":"Stiftung Umweltenergierecht","article_modified_time":"2025-08-19T10:16:31+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/10\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide.pdf","url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/10\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide.pdf","name":"Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide - Stiftung Umweltenergierecht","isPartOf":{"@id":"https:\/\/stiftung-umweltenergierecht.de\/#website"},"datePublished":"2018-10-31T11:38:29+00:00","dateModified":"2025-08-19T10:16:31+00:00","breadcrumb":{"@id":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/10\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide.pdf#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/10\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide.pdf"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/10\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide.pdf#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stiftung-umweltenergierecht.de\/en\/"},{"@type":"ListItem","position":2,"name":"Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide"}]},{"@type":"WebSite","@id":"https:\/\/stiftung-umweltenergierecht.de\/#website","url":"https:\/\/stiftung-umweltenergierecht.de\/","name":"Stiftung Umweltenergierecht","description":"Eine weitere WordPress-Seite","publisher":{"@id":"https:\/\/stiftung-umweltenergierecht.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stiftung-umweltenergierecht.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stiftung-umweltenergierecht.de\/#organization","name":"Stiftung Umweltenergierecht","url":"https:\/\/stiftung-umweltenergierecht.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stiftung-umweltenergierecht.de\/#\/schema\/logo\/image\/","url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2016\/03\/logo-SUER_web.jpg","contentUrl":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2016\/03\/logo-SUER_web.jpg","width":493,"height":53,"caption":"Stiftung Umweltenergierecht"},"image":{"@id":"https:\/\/stiftung-umweltenergierecht.de\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/10\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide.pdf'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/10\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide-pdf-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"file","mime_type":"application\/pdf","media_details":{"sizes":{"thumbnail":{"file":"Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide-pdf-150x113.jpg","width":150,"height":113,"mime_type":"image\/jpeg","source_url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/10\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide-pdf-150x113.jpg"},"medium":{"file":"Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide-pdf-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/10\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide-pdf-300x225.jpg"},"large":{"file":"Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide-pdf-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/10\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide-pdf-1024x768.jpg"},"full":{"file":"Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide-pdf.jpg","width":1280,"height":960,"mime_type":"application\/pdf","source_url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/10\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide-pdf.jpg"}}},"post":null,"source_url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/10\/Stiftung_Umweltenergierecht_20181023_FokusEU_Neuer_EU-Rechtsrahmen_Ide.pdf","_links":{"self":[{"href":"https:\/\/stiftung-umweltenergierecht.de\/en\/wp-json\/wp\/v2\/media\/17276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stiftung-umweltenergierecht.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/stiftung-umweltenergierecht.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/stiftung-umweltenergierecht.de\/en\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/stiftung-umweltenergierecht.de\/en\/wp-json\/wp\/v2\/comments?post=17276"}]}}