{"id":10013,"date":"2017-01-20T11:04:35","date_gmt":"2017-01-20T10:04:35","guid":{"rendered":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg"},"modified":"2017-01-20T11:04:35","modified_gmt":"2017-01-20T10:04:35","slug":"cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit-2","status":"inherit","type":"attachment","link":"https:\/\/stiftung-umweltenergierecht.de\/en\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit-2\/","title":{"rendered":"cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit"},"author":45,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-10013","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit - Stiftung Umweltenergierecht<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit - Stiftung Umweltenergierecht\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Stiftung Umweltenergierecht\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"371\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg\",\"url\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg\",\"name\":\"cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit - Stiftung Umweltenergierecht\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/#website\"},\"datePublished\":\"2017-01-20T10:04:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/#website\",\"url\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/\",\"name\":\"Stiftung Umweltenergierecht\",\"description\":\"Eine weitere WordPress-Seite\",\"publisher\":{\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/#organization\",\"name\":\"Stiftung Umweltenergierecht\",\"url\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/logo-SUER_web.jpg\",\"contentUrl\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/logo-SUER_web.jpg\",\"width\":493,\"height\":53,\"caption\":\"Stiftung Umweltenergierecht\"},\"image\":{\"@id\":\"https:\\\/\\\/stiftung-umweltenergierecht.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit - Stiftung Umweltenergierecht","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg","og_locale":"en_US","og_type":"article","og_title":"cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit - Stiftung Umweltenergierecht","og_url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg","og_site_name":"Stiftung Umweltenergierecht","og_image":[{"width":250,"height":371,"url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg","url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg","name":"cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit - Stiftung Umweltenergierecht","isPartOf":{"@id":"https:\/\/stiftung-umweltenergierecht.de\/#website"},"datePublished":"2017-01-20T10:04:35+00:00","breadcrumb":{"@id":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stiftung-umweltenergierecht.de\/en\/"},{"@type":"ListItem","position":2,"name":"cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit"}]},{"@type":"WebSite","@id":"https:\/\/stiftung-umweltenergierecht.de\/#website","url":"https:\/\/stiftung-umweltenergierecht.de\/","name":"Stiftung Umweltenergierecht","description":"Eine weitere WordPress-Seite","publisher":{"@id":"https:\/\/stiftung-umweltenergierecht.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stiftung-umweltenergierecht.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stiftung-umweltenergierecht.de\/#organization","name":"Stiftung Umweltenergierecht","url":"https:\/\/stiftung-umweltenergierecht.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stiftung-umweltenergierecht.de\/#\/schema\/logo\/image\/","url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2016\/03\/logo-SUER_web.jpg","contentUrl":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2016\/03\/logo-SUER_web.jpg","width":493,"height":53,"caption":"Stiftung Umweltenergierecht"},"image":{"@id":"https:\/\/stiftung-umweltenergierecht.de\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"202\" height=\"300\" src=\"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit-202x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit-202x300.jpg 202w, https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit-160x237.jpg 160w, https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit-235x349.jpg 235w, https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg 250w\" sizes=\"auto, (max-width: 202px) 100vw, 202px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":250,"height":371,"file":"2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg","sizes":{"thumbnail":{"file":"cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit-150x150.jpg"},"medium":{"file":"cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit-202x300.jpg","width":202,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit-202x300.jpg"},"mitarbeiter-thumb":{"file":"cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit-92x92.jpg","width":92,"height":92,"mime_type":"image\/jpeg","source_url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit-92x92.jpg"},"partner-logo":{"file":"cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit-160x237.jpg","width":160,"height":237,"mime_type":"image\/jpeg","source_url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit-160x237.jpg"},"geburtstag-thumb":{"file":"cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit-235x349.jpg","width":235,"height":349,"mime_type":"image\/jpeg","source_url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit-235x349.jpg"},"full":{"file":"cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg","width":250,"height":371,"mime_type":"image\/jpeg","source_url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/stiftung-umweltenergierecht.de\/wp-content\/uploads\/2018\/01\/cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg","filename":"cover_schuer_006_wirtschaftliche_zumutbarkeit_ringel_250px_breit.jpg","filesize":58832,"_links":{"self":[{"href":"https:\/\/stiftung-umweltenergierecht.de\/en\/wp-json\/wp\/v2\/media\/10013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stiftung-umweltenergierecht.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/stiftung-umweltenergierecht.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/stiftung-umweltenergierecht.de\/en\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/stiftung-umweltenergierecht.de\/en\/wp-json\/wp\/v2\/comments?post=10013"}]}}